{"id":282,"date":"2023-04-03T13:35:45","date_gmt":"2023-04-03T11:35:45","guid":{"rendered":"https:\/\/erranet.org\/annual-conference\/?page_id=282"},"modified":"2023-04-03T13:37:52","modified_gmt":"2023-04-03T11:37:52","slug":"erra-events-policy","status":"publish","type":"page","link":"https:\/\/erranet.org\/annual-conference\/erra-events-policy\/","title":{"rendered":"ERRA Events Policy"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-282","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ERRA Events Policy - ERRA - Annual Conference<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/erranet.org\/annual-conference\/erra-events-policy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ERRA Events Policy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/erranet.org\/annual-conference\/erra-events-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"ERRA - Annual Conference\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-03T11:37:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/erranet.org\\\/annual-conference\\\/erra-events-policy\\\/\",\"url\":\"https:\\\/\\\/erranet.org\\\/annual-conference\\\/erra-events-policy\\\/\",\"name\":\"ERRA Events Policy - ERRA - Annual Conference\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erranet.org\\\/annual-conference\\\/#website\"},\"datePublished\":\"2023-04-03T11:35:45+00:00\",\"dateModified\":\"2023-04-03T11:37:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/erranet.org\\\/annual-conference\\\/erra-events-policy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/erranet.org\\\/annual-conference\\\/erra-events-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/erranet.org\\\/annual-conference\\\/erra-events-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/erranet.org\\\/annual-conference\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ERRA Events Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/erranet.org\\\/annual-conference\\\/#website\",\"url\":\"https:\\\/\\\/erranet.org\\\/annual-conference\\\/\",\"name\":\"ERRA - Annual Conference\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/erranet.org\\\/annual-conference\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ERRA Events Policy - ERRA - Annual Conference","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/erranet.org\/annual-conference\/erra-events-policy\/","og_locale":"en_US","og_type":"article","og_title":"ERRA Events Policy","og_url":"https:\/\/erranet.org\/annual-conference\/erra-events-policy\/","og_site_name":"ERRA - Annual Conference","article_modified_time":"2023-04-03T11:37:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/erranet.org\/annual-conference\/erra-events-policy\/","url":"https:\/\/erranet.org\/annual-conference\/erra-events-policy\/","name":"ERRA Events Policy - ERRA - Annual Conference","isPartOf":{"@id":"https:\/\/erranet.org\/annual-conference\/#website"},"datePublished":"2023-04-03T11:35:45+00:00","dateModified":"2023-04-03T11:37:52+00:00","breadcrumb":{"@id":"https:\/\/erranet.org\/annual-conference\/erra-events-policy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/erranet.org\/annual-conference\/erra-events-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/erranet.org\/annual-conference\/erra-events-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/erranet.org\/annual-conference\/"},{"@type":"ListItem","position":2,"name":"ERRA Events Policy"}]},{"@type":"WebSite","@id":"https:\/\/erranet.org\/annual-conference\/#website","url":"https:\/\/erranet.org\/annual-conference\/","name":"ERRA - Annual Conference","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/erranet.org\/annual-conference\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/erranet.org\/annual-conference\/wp-json\/wp\/v2\/pages\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erranet.org\/annual-conference\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/erranet.org\/annual-conference\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/erranet.org\/annual-conference\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/erranet.org\/annual-conference\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":1,"href":"https:\/\/erranet.org\/annual-conference\/wp-json\/wp\/v2\/pages\/282\/revisions"}],"predecessor-version":[{"id":285,"href":"https:\/\/erranet.org\/annual-conference\/wp-json\/wp\/v2\/pages\/282\/revisions\/285"}],"wp:attachment":[{"href":"https:\/\/erranet.org\/annual-conference\/wp-json\/wp\/v2\/media?parent=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}